{"id":1833,"date":"2024-12-15T09:41:01","date_gmt":"2024-12-15T14:41:01","guid":{"rendered":"https:\/\/chapters.theprimetimersww.com\/baltimore\/venue\/reginald-f-lewis-museum\/"},"modified":"2024-12-15T09:41:01","modified_gmt":"2024-12-15T14:41:01","slug":"reginald-f-lewis-museum","status":"publish","type":"tribe_venue","link":"https:\/\/chapters.theprimetimersww.com\/baltimore\/venue\/reginald-f-lewis-museum\/","title":{"rendered":"Reginald F. Lewis Museum"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"template":"","meta":{"footnotes":""},"class_list":["post-1833","tribe_venue","type-tribe_venue","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/chapters.theprimetimersww.com\/baltimore\/wp-json\/wp\/v2\/tribe_venue\/1833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chapters.theprimetimersww.com\/baltimore\/wp-json\/wp\/v2\/tribe_venue"}],"about":[{"href":"https:\/\/chapters.theprimetimersww.com\/baltimore\/wp-json\/wp\/v2\/types\/tribe_venue"}],"author":[{"embeddable":true,"href":"https:\/\/chapters.theprimetimersww.com\/baltimore\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":0,"href":"https:\/\/chapters.theprimetimersww.com\/baltimore\/wp-json\/wp\/v2\/tribe_venue\/1833\/revisions"}],"wp:attachment":[{"href":"https:\/\/chapters.theprimetimersww.com\/baltimore\/wp-json\/wp\/v2\/media?parent=1833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}