{"id":2643,"date":"2022-02-26T23:04:37","date_gmt":"2022-02-27T05:04:37","guid":{"rendered":"https:\/\/chapters.theprimetimersww.com\/wichita\/?post_type=tribe_events&#038;p=2643"},"modified":"2022-02-26T23:04:37","modified_gmt":"2022-02-27T05:04:37","slug":"daylight-savings-begins","status":"publish","type":"tribe_events","link":"https:\/\/chapters.theprimetimersww.com\/wichita\/event\/daylight-savings-begins\/","title":{"rendered":"Daylight Savings Begins"},"content":{"rendered":"<p>Enough said.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enough said.<\/p>\n","protected":false},"author":5,"featured_media":1742,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-2643","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/chapters.theprimetimersww.com\/wichita\/wp-json\/wp\/v2\/tribe_events\/2643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chapters.theprimetimersww.com\/wichita\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/chapters.theprimetimersww.com\/wichita\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/chapters.theprimetimersww.com\/wichita\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":1,"href":"https:\/\/chapters.theprimetimersww.com\/wichita\/wp-json\/wp\/v2\/tribe_events\/2643\/revisions"}],"predecessor-version":[{"id":2644,"href":"https:\/\/chapters.theprimetimersww.com\/wichita\/wp-json\/wp\/v2\/tribe_events\/2643\/revisions\/2644"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chapters.theprimetimersww.com\/wichita\/wp-json\/wp\/v2\/media\/1742"}],"wp:attachment":[{"href":"https:\/\/chapters.theprimetimersww.com\/wichita\/wp-json\/wp\/v2\/media?parent=2643"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chapters.theprimetimersww.com\/wichita\/wp-json\/wp\/v2\/tags?post=2643"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/chapters.theprimetimersww.com\/wichita\/wp-json\/wp\/v2\/tribe_events_cat?post=2643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}