{"id":4663,"date":"2024-09-27T00:14:38","date_gmt":"2024-09-27T05:14:38","guid":{"rendered":"https:\/\/chapters.theprimetimersww.com\/wichita\/?post_type=tribe_events&#038;p=4663"},"modified":"2024-09-27T00:14:38","modified_gmt":"2024-09-27T05:14:38","slug":"solidarity-sunday-anti-violence-initiative","status":"publish","type":"tribe_events","link":"https:\/\/chapters.theprimetimersww.com\/wichita\/event\/solidarity-sunday-anti-violence-initiative\/","title":{"rendered":"Solidarity Sunday | Anti Violence Initiative"},"content":{"rendered":"<p>There is no place in the church, or world for hate, denigration, violence, or oppression.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>There is no place in the church, or world for hate, denigration, violence, or oppression.<\/p>\n","protected":false},"author":5,"featured_media":716,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-4663","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/chapters.theprimetimersww.com\/wichita\/wp-json\/wp\/v2\/tribe_events\/4663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chapters.theprimetimersww.com\/wichita\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/chapters.theprimetimersww.com\/wichita\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/chapters.theprimetimersww.com\/wichita\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":1,"href":"https:\/\/chapters.theprimetimersww.com\/wichita\/wp-json\/wp\/v2\/tribe_events\/4663\/revisions"}],"predecessor-version":[{"id":4664,"href":"https:\/\/chapters.theprimetimersww.com\/wichita\/wp-json\/wp\/v2\/tribe_events\/4663\/revisions\/4664"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chapters.theprimetimersww.com\/wichita\/wp-json\/wp\/v2\/media\/716"}],"wp:attachment":[{"href":"https:\/\/chapters.theprimetimersww.com\/wichita\/wp-json\/wp\/v2\/media?parent=4663"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chapters.theprimetimersww.com\/wichita\/wp-json\/wp\/v2\/tags?post=4663"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/chapters.theprimetimersww.com\/wichita\/wp-json\/wp\/v2\/tribe_events_cat?post=4663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}